{"id":1637,"date":"2017-11-11T15:49:42","date_gmt":"2017-11-11T14:49:42","guid":{"rendered":"http:\/\/enroutepourlinconnu.com\/?p=1637"},"modified":"2019-02-01T16:23:09","modified_gmt":"2019-02-01T15:23:09","slug":"new-delhi-nouveau-monde","status":"publish","type":"post","link":"https:\/\/enroutepourlinconnu.com\/index.php\/2017\/11\/11\/new-delhi-nouveau-monde\/","title":{"rendered":"New Delhi, nouveau monde"},"content":{"rendered":"<p><em>Ambiance musicale : Channa Mereya &#8211; Pritam<\/em><\/p>\n<p>Pour la premi\u00e8re fois depuis mon d\u00e9part de France, j\u2019ai pris un vol pour rejoindre ma prochaine destination, en l\u2019occurrence <strong>New Delhi<\/strong>, et l\u2019Inde en toile de fond. Il n\u2019\u00e9tait sans doute pas impossible de passer par la fronti\u00e8re terrestre entre les deux pays, mais cela requ\u00e9rait du temps, de l\u2019argent et de la chance, des tensions ethniques existant des deux c\u00f4t\u00e9s de la fronti\u00e8re et des permis \u00e9tant n\u00e9cessaires.<\/p>\n<p>Ce vol m\u2019a rappel\u00e9 \u00e0 quel point ma libert\u00e9 de mouvement avait \u00e9t\u00e9 totale (ou presque) jusqu\u2019\u00e0 pr\u00e9sent, puisque je n\u2019avais eu aucune contrainte de date pour des transports et que la plupart des r\u00e9servations se faisait du jour pour le lendemain. Le fait de devoir pr\u00e9voir longtemps \u00e0 l\u2019avance et de rentrer dans un cadre rigide se heurtait violemment \u00e0 cette facult\u00e9.<\/p>\n<p><!--more--><\/p>\n<p>A peine arriv\u00e9, c\u2019est un tourbillon de sensations et une exp\u00e9rience multi-sensorielle qui s\u2019est offerte \u00e0 moi. Ce que l\u2019on voit, ce que l\u2019on entend, ce que l\u2019on sent, ce que l\u2019on go\u00fbte, ce que l\u2019on touche&nbsp;: tout est diff\u00e9rent et\/ou pouss\u00e9 \u00e0 son extr\u00eame.<\/p>\n<p>J\u2019ai donc \u00e9t\u00e9 accueilli par une \u00e9paisse couche de pollution et de poussi\u00e8re, dans une chaleur un brin humide, un oppressant tintamarre de klaxons, qu\u2019ils proviennent des <strong>auto-rickshaws<\/strong> (<em>tuk-tuk<\/em>) ou des autres v\u00e9hicules qui s\u2019engouffrent absolument partout, dans une course effr\u00e9n\u00e9e.<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1638\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090441-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1639\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090542-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1640\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090500-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1641\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090502-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Les sollicitations \u00e9taient nombreuses et il \u00e9tait difficile de faire quelques pas dans <strong>Paharganj<\/strong> sans se faire arr\u00eater une dizaine de fois, sans oublier de r\u00e9pondre poliment \u00e0 toutes les propositions. De nombreuses nationalit\u00e9s \u00e9taient pr\u00e9sentes dans ce quartier o\u00f9 beaucoup de voyageurs ind\u00e9pendants convergent, et j\u2019ai \u00e9t\u00e9 surpris par le nombre de Japonais et d\u2019Isra\u00e9liens.<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1642\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110407-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La rue est un march\u00e9 \u00e0 ciel ouvert, o\u00f9 l\u2019on peut quasiment tout trouver, mais surtout se retrouver face \u00e0 des odeurs (viande, poisson, \u00e9pices, etc.) assez fortes et des sc\u00e8nes assez d\u00e9routantes, comme des mendiants dans un \u00e9tat d\u2019indigence absolue ou des vaches, consid\u00e9r\u00e9es sacr\u00e9es par les Hindous, d\u00e9ambulant all\u00e8grement en plein milieu du reste de l\u2019agitation.<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1643\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110400-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1644\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1110405-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>C\u2019est aussi une gastronomie, une cuisine compl\u00e8tement diff\u00e9rente (et de laquelle j\u2019\u00e9tais assez peu familier) qu\u2019il a fallu tester, pour trouver mes pr\u00e9f\u00e9rences. Le th\u00e9 (<strong><em>cha\u00ef<\/em><\/strong>), les currys, les diff\u00e9rentes formes de pain (<strong><em>nan, roti, chapati, parantha<\/em><\/strong>), les brochettes (<strong><em>tikka<\/em><\/strong>), les cuissons au four (<strong><em>tandoori<\/em><\/strong>) mais surtout les \u00e9pices (<strong><em>masala<\/em><\/strong>) et tous les noms utilis\u00e9s.<\/p>\n<p>Une grande importance est accord\u00e9e au r\u00e9gime v\u00e9g\u00e9tarien, d\u2019une part du fait des croyances religieuses hindouistes et bouddhistes, et d\u2019autre part par n\u00e9cessit\u00e9&nbsp;: il n\u2019est pas \u00e9vident de payer aussi cher pour de la viande\u2026<\/p>\n<p>Apr\u00e8s quelques jours \u00ab&nbsp;d\u2019acclimatation&nbsp;\u00bb et de rattrapage d\u2019\u00e9criture de blog, je suis parti \u00e0 l\u2019assaut de la ville avec Claudio, vieux baroudeur italien et Elias, cyclotouriste dans une \u00e9pop\u00e9e assez g\u00e9niale&nbsp;: rejoindre la ville aux antipodes de son origine, Tol\u00e8de, qui se situe en Nouvelle-Z\u00e9lande.<\/p>\n<p>Ce premier trajet en tuk-tuk nous a men\u00e9s au c\u0153ur du <strong>Vieux Delhi<\/strong>, jusqu\u2019\u00e0 <strong>Jama Masjid<\/strong>, une magnifique mosqu\u00e9e du XVII\u00e8me si\u00e8cle qui peut contenir jusqu\u2019\u00e0 vingt-cinq mille personnes, ce qui en fait la plus grande d\u2019Inde. Il s\u2019agit d\u2019une des constructions de <strong>Shah Jahan<\/strong>, un des plus grands empereurs <strong>moghols<\/strong>, ces derniers ayant r\u00e9gn\u00e9 du XVI\u00e8me au XVIII\u00e8me si\u00e8cle sur l\u2019Inde.<\/p>\n<div style=\"width: 629px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1637-1\" width=\"629\" height=\"354\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090421.mp4?_=1\" \/><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090421.mp4\">https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090421.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Juste avant l\u2019entr\u00e9e, une sc\u00e8ne nous a interloqu\u00e9s&nbsp;: des gens, manifestement dans le besoin, jetaient \u00e0 l\u2019envi des bouts de viande \u00e0 des faucons qui tournoyaient au-dessus d\u2019eux. Quand on a pos\u00e9 la question de savoir ce qu\u2019il se passait, nous avons compris qu\u2019il s\u2019agissait d\u2019un don \u00e0 la divinit\u00e9 repr\u00e9sent\u00e9e par les rapaces.<\/p>\n<div style=\"width: 629px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1637-2\" width=\"629\" height=\"354\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090424.mp4?_=2\" \/><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090424.mp4\">https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090424.mp4<\/a><\/video><\/div>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1647\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090427-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1648\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090428-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1649\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090432-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1650\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090437-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1651\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090453-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Plus tard, c\u2019est le <strong>Fort Rouge<\/strong> qui a attir\u00e9 notre attention. Edifi\u00e9e par le m\u00eame empereur entre 1636 et 1648, cette forteresse fut cr\u00e9\u00e9e pour prot\u00e9ger sa nouvelle ville capitale, <strong>Shahjahanabad (ancienne Delhi)<\/strong>, gr\u00e2ce \u00e0 une enceinte de dix-huit m\u00e8tres de haut. Les monuments, en marbre et en gr\u00e8s rouge, pr\u00e9sentent une architecture remarquable.<\/p>\n<p>Au bord de la rivi\u00e8re <strong>Yamuna<\/strong>, qui en alimente les jardins en eau, ce lieu, symbole de l\u2019<strong>ind\u00e9pendance<\/strong> en 1947, est celui depuis lequel le premier ministre s\u2019adresse tous les ans \u00e0 la nation.<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1652\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090464-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1653\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090475-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1654\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090476-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1655\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090496-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>La journ\u00e9e s\u2019est termin\u00e9e dans le calme des <strong>jardins de Lodi<\/strong>, sorte d\u2019enclave paisible au milieu de la ville, pleine de v\u00e9g\u00e9tation et de personnes d\u00e9ambulant sereinement. Le contraste \u00e9tait assez saisissant avec la <strong>Porte de l\u2019Inde<\/strong>, m\u00e9morial en forme d\u2019arche pour les Indiens morts lors de la Premi\u00e8re Guerre mondiale, o\u00f9 les gens s\u2019agglutinaient pour prendre les indispensables selfies.<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1656\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090508-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1657\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090512-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a> <a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1658\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090513-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1659\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090519-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1660\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090521-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ma derni\u00e8re visite de monument s\u2019est faite des semaines plus tard, de retour \u00e0 New Delhi avant de m\u2019envoler pour d\u2019autres aventures. Revenir \u00e0 Paharganj, retrouver ce quartier, mes <strong><em>dhabas<\/em><\/strong> et leurs propri\u00e9taires (ces cantines o\u00f9 je me d\u00e9lectais de plats dont le degr\u00e9 d\u2019\u00e9pices ne m\u2019effrayait plus autant), mon coiffeur, tout cela avait un air de zone de confort.<\/p>\n<p>C\u2019est dans ce m\u00e9tro tellement diff\u00e9rent du reste du pays (climatis\u00e9, propre, plut\u00f4t bien organis\u00e9) que j\u2019ai rejoint le <strong>temple<\/strong> <strong>Akshardham<\/strong>, temple hindou qui se veut le centre des traditions et des valeurs culturelles indiennes. D\u00e9di\u00e9 \u00e0 <strong>Bhagwan Swaminarayan<\/strong>, le complexe s\u2019articule autour d\u2019un monument central fait de pierre rose et de marbre blanc, massif, et dont les piliers et les d\u00f4mes sont minutieusement sculpt\u00e9s (vingt mille figures l\u2019orneraient).<\/p>\n<p>Le c\u00f4t\u00e9 r\u00e9cent (2005) du centre tranchait avec la culture mill\u00e9naire du pays qu\u2019il devait repr\u00e9senter. Aucune photo n\u2019a \u00e9t\u00e9 possible en raison des restrictions tr\u00e8s fortes \u00e0 l\u2019entr\u00e9e, mais c\u2019est un espace qui valait d\u00e9finitivement le coup d\u2019\u0153il.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1661\" src=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-1024x768.jpg\" alt=\"\" width=\"629\" height=\"472\" srcset=\"https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-1024x768.jpg 1024w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-300x225.jpg 300w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-768x576.jpg 768w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-900x675.jpg 900w, https:\/\/enroutepourlinconnu.com\/wp-content\/uploads\/2017\/11\/P1090539-1280x960.jpg 1280w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ambiance musicale : Channa Mereya &#8211; Pritam Pour la premi\u00e8re fois depuis mon d\u00e9part de France, j\u2019ai pris un vol pour rejoindre ma prochaine destination, en l\u2019occurrence New Delhi, et l\u2019Inde en toile de fond. Il n\u2019\u00e9tait sans doute pas impossible de passer par la fronti\u00e8re terrestre entre les deux pays, mais cela requ\u00e9rait du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inde"],"_links":{"self":[{"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/posts\/1637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/comments?post=1637"}],"version-history":[{"count":2,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions"}],"predecessor-version":[{"id":3141,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/posts\/1637\/revisions\/3141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/media\/1661"}],"wp:attachment":[{"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/media?parent=1637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/categories?post=1637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enroutepourlinconnu.com\/index.php\/wp-json\/wp\/v2\/tags?post=1637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}